{"id":264915,"date":"2018-08-02T13:35:26","date_gmt":"2018-08-02T10:35:26","guid":{"rendered":"https:\/\/unitedwithisrael.org\/?p=264915"},"modified":"2018-08-03T11:44:49","modified_gmt":"2018-08-03T08:44:49","slug":"temoignage-exclusif-etre-chretien-en-zone-controlee-par-lautorite-palestinienne","status":"publish","type":"post","link":"https:\/\/unitedwithisrael.org\/fr\/temoignage-exclusif-etre-chretien-en-zone-controlee-par-lautorite-palestinienne\/","title":{"rendered":"T\u00e9moignage exclusif: Etre chr\u00e9tien en zone contr\u00f4l\u00e9e par l&rsquo;Autorit\u00e9 Palestinienne"},"content":{"rendered":"<p class=\"lead\"><em><strong>\u00abJe n&rsquo;ai jamais \u00e9t\u00e9 victime de discrimination en tant que chr\u00e9tienne vivant en Isra\u00ebl\u00bb, explique Lela Gilbert.<\/strong><\/em><\/p>\n<p><em>Par: Lela Gilbert, en exclusivit\u00e9 pour Unis avec Isra\u00ebl<\/em><\/p>\n<p>Un article r\u00e9cent, \u00ab\u00a0<em>Les chr\u00e9tiens ne sont plus les bienvenus en Isra\u00ebl &#8211; Des terres confisqu\u00e9es pour les colonies isra\u00e9liennes<\/em>\u00a0\u00bb (aucun nom d&rsquo;auteur n&rsquo;est fourni) a \u00e9t\u00e9 publi\u00e9 par ANA Newswire le 23 juillet 2018.<\/p>\n<p>Il a ensuite \u00e9t\u00e9 envoy\u00e9 \u00e0 Unis avec Isra\u00ebl.<\/p>\n<p>L&rsquo;auteur y affirme que les chr\u00e9tiens palestiniens sont priv\u00e9s de libert\u00e9 de culte sur leurs lieux saints. De plus, on y explique que leur population diminue du fait des actions discriminatoires men\u00e9es par Isra\u00ebl \u00e0 l&rsquo;\u00e9gard des chr\u00e9tiens.<\/p>\n<p>En ce qui concerne la confiscation des terres? Ce sujet n&rsquo;est pas du tout abord\u00e9 dans l&rsquo;article &#8211; c&rsquo;est probablement parce que ce n&rsquo;est pas vrai.<\/p>\n<p>Je suis une chr\u00e9tienne am\u00e9ricaine ayant v\u00e9cu plus de 10 ans \u00e0 J\u00e9rusalem, et j&rsquo;ai quitt\u00e9 le pays en 2017. J&rsquo;ai non seulement plus d&rsquo;une d\u00e9cennie d&rsquo;exp\u00e9rience en mati\u00e8re de relations entre isra\u00e9liens et chr\u00e9tiens, mais je suis aussi chercheur et \u00e9crivain au sujet de ces probl\u00e8mes.<\/p>\n<p>Les accusations contenues dans l&rsquo;article de l&rsquo;ANA ne nous sont pas inconnues &#8211; elles sont enti\u00e8rement reconnaissables en tant que propagande anti-isra\u00e9lienne typique et mal document\u00e9e. Je vais fournir plus d&rsquo;informations \u00e0 ce sujet dans un instant.<\/p>\n<p>Mais avant cela, permettez-moi de dire que je n&rsquo;ai jamais \u00e9t\u00e9 discrimin\u00e9e en tant que chr\u00e9tien vivant en Isra\u00ebl. Comme tous les r\u00e9sidents non isra\u00e9liens, il m&rsquo;a \u00e9t\u00e9 demand\u00e9 de mettre \u00e0 jour r\u00e9guli\u00e8rement mon visa de visiteur, ce qui impliquait parfois de fournir une documentation sur mes revenus, mon travail et la location de mon appartement.<\/p>\n<p>Toutes les nations civilis\u00e9es exigent une documentation similaire, sinon plus.<\/p>\n<p>Par ailleurs, les accusations selon lesquelles les chr\u00e9tiens ne peuvent pas acc\u00e9der facilement \u00e0 leurs lieux saints sont tout simplement fausses. Ces deux facteurs cl\u00e9s manquent \u00e0 l&rsquo;article de l&rsquo;ANA.<\/p>\n<h2>Isra\u00ebl a rendu J\u00e9rusalem accessible \u00e0 tous<\/h2>\n<p>Tout d\u2019abord, il est essentiel de noter que jusqu\u2019\u00e0 ce qu\u2019Isra\u00ebl obtienne ses droits sur J\u00e9rusalem-Est &#8211; apr\u00e8s sa victoire lors de la guerre de 1967 -, ni les chr\u00e9tiens ni les juifs ne pouvaient visiter des sites sacr\u00e9s, sans autorisation expresse du Gouvernement jordanien.<\/p>\n<p>Contrairement \u00e0 aujourd&rsquo;hui, il n&rsquo;existait aucune libert\u00e9 &#8211; pour les r\u00e9sidents isra\u00e9liens ou les touristes, juifs ou chr\u00e9tiens &#8211; de se promener paisiblement pr\u00e8s de la porte de Jaffa et de fl\u00e2ner dans l&rsquo;\u00e9glise du Saint-S\u00e9pulcre et dans le quartier chr\u00e9tien, ou encore de visiter les synagogues du quartier juif.<\/p>\n<p>Premi\u00e8rement, les synagogues avaient toutes disparu &#8211; souffl\u00e9es par les Jordaniens.<\/p>\n<p>Deuxi\u00e8mement, il y existait une zone militaire de no man&rsquo;s land entre la vieille ville de J\u00e9rusalem et le secteur isra\u00e9lien occidental de la ville. Le passage d&rsquo;un endroit \u00e0 un autre rendait impossible m\u00eame le p\u00e8lerinage le plus pieux et le plus innocent.<\/p>\n<h2>Les barri\u00e8res: une protection contre le terrorisme<\/h2>\n<p>Alors, de quoi l&rsquo;article se plaint-il? Voici ce que l&rsquo;auteur \u00e9crit:<\/p>\n<p>\u00ab\u00a0.<em>.. Un pasteur catholique a d\u00e9crit comment, pendant P\u00e2ques, l&rsquo;une des p\u00e9riodes les plus saintes de l&rsquo;ann\u00e9e pour les chr\u00e9tiens, l&rsquo;\u00e9glise sacr\u00e9e du Saint-S\u00e9pulcre &#8211; site central de la mort, de la crucifixion et de la r\u00e9surrection de J\u00e9sus &#8211; ressemble \u00e0 une caserne militaire. Les barri\u00e8res sont install\u00e9es t\u00f4t le matin pour emp\u00eacher les gens de sortir de la cour de l&rsquo;\u00e9glise.<\/em><\/p>\n<p><em>Des officiers de l&rsquo;arm\u00e9e isra\u00e9lienne sont pr\u00e9sents autour des portes de la vieille ville et des passages qui m\u00e8nent au Saint-S\u00e9pulcre, ainsi qu&rsquo;\u00e0 l&rsquo;int\u00e9rieur m\u00eame de l&rsquo;\u00e9glise et sur son toit. Ces mesures restreignent la libert\u00e9 de mouvement des Palestiniens, emp\u00eachant les chr\u00e9tiens palestiniens de se rendre \u00e0 l\u2019Eglise pendant cette p\u00e9riode propice. M\u00eame les pr\u00eatres ne sont pas autoris\u00e9s \u00e0 se d\u00e9placer librement.<\/em> \u00a0\u00bb<\/p>\n<p>Alors pourquoi, semble se demander l&rsquo;auteur, une pr\u00e9sence militaire, des barri\u00e8res et des mesures de contr\u00f4le des foules seraient-elles en place?<\/p>\n<p>Pour quiconque vit en Isra\u00ebl, c&rsquo;est tr\u00e8s \u00e9vident: la police et l&rsquo;arm\u00e9e, les barri\u00e8res et le contr\u00f4le des foules sont destin\u00e9s \u00e0 \u00e9viter les attaques terroristes dans des lieux tr\u00e8s fr\u00e9quent\u00e9s. Ils ont pour but de prot\u00e9ger les p\u00e8lerins et les autres visiteurs des agressions.<\/p>\n<p>Tous les visiteurs &#8211; Am\u00e9ricains, Europ\u00e9ens, Russes, Africains, Asiatiques de l\u2019Est et Chr\u00e9tiens Palestiniens &#8211; doivent faire la queue et se soumettre \u00e0 une avanc\u00e9e lente.<\/p>\n<p>S&rsquo;il n&rsquo;y avait pas eu d&rsquo;attaques arabes contre les juifs depuis l&rsquo;ind\u00e9pendance d&rsquo;Isra\u00ebl de 1948 jusqu&rsquo;\u00e0 aujourd&rsquo;hui; s&rsquo;il n&rsquo;y avait pas eu de premi\u00e8re Intifada dans les ann\u00e9es 1990; S&rsquo;il n&rsquo;y avait pas eu de deuxi\u00e8me Intifada, \u00e0 partir de 2000 &#8211; au cours desquelles d&rsquo;un millier d&rsquo;Isra\u00e9liens ont \u00e9t\u00e9 tu\u00e9s &#8211; il n&rsquo;y aurait pas besoin de ces d\u00e9fenses soigneusement planifi\u00e9es.<\/p>\n<p>Il en va de m\u00eame pour le passage de Bethl\u00e9em et d\u2019autres villes contr\u00f4l\u00e9es par l\u2019Autorit\u00e9 Palestinienne dans l\u2019\u00c9tat d\u2019Isra\u00ebl. Des permis sont requis.<\/p>\n<p>Cela est \u00e9galement d\u00fb aux attaques terroristes contre des civils isra\u00e9liens &#8211; non seulement dans les lieux saints, mais aussi dans les caf\u00e9s, les h\u00f4tels, les zones commerciales et tout autre lieu de rassemblement.<\/p>\n<p>Il est regrettable que de telles mesures compliqu\u00e9es doivent \u00eatre prises, mais c&rsquo;est la r\u00e9alit\u00e9. Et elle est bas\u00e9e sur des incidents r\u00e9p\u00e9t\u00e9s d\u2019effusions de sang perp\u00e9tr\u00e9es par des terroristes arabes &#8211; la plupart d\u2019entre eux \u00e9tant des radicaux musulmans.<\/p>\n<p>Tout le monde paie le prix de leurs m\u00e9faits &#8211; y compris les musulmans pacifiques.<\/p>\n<h2>Les chr\u00e9tiens fuient les territoires palestiniens<\/h2>\n<p>En ce qui concerne le reste des plaintes \u00e9voau\u00e9es par l&rsquo;article, en particulier concernant le d\u00e9part des chr\u00e9tiens des territoires palestiniens, avec la permission du Philos Project, je citerai mon propre article \u00ab\u00a0<em>Carnet de J\u00e9rusalem: la lutte silencieuse des chr\u00e9tiens de Bethl\u00e9em\u00a0\u00bb.<\/em><\/p>\n<p>Pour les\u00a0 int\u00e9ress\u00e9s, ce qui suit aborde ces probl\u00e8mes.<\/p>\n<p>Lundi 1er ao\u00fbt 2016<\/p>\n<p>Il est \u00e9tonnamment rapide en voiture de se rendre deJ\u00e9rusalem-Ouest \u00e0 Bethl\u00e9em &#8211; 10 ou 15 minutes au maximum. Mais par une chaude nuit d&rsquo;\u00e9t\u00e9, il y a quelques semaines, j&rsquo;avais l&rsquo;impression d&rsquo;avoir voyag\u00e9 des ann\u00e9es-lumi\u00e8re en partant d&rsquo;un quartier anim\u00e9 de J\u00e9rusalem et d&rsquo;arriver dans une modeste maison dans un village tranquille de Bethl\u00e9em.<\/p>\n<p>Dans mon esprit, la rue verdoyante et bien \u00e9clair\u00e9e de laquelle j&rsquo;\u00e9tais partie avait \u00e9t\u00e9 rapidement juxtapos\u00e9e \u00e0 ma destination sombre. Cela me rappelait un voyage que j&rsquo;avais effectu\u00e9 de Berlin-Ouest \u00e0 Berlin-Est \u00e0 la fin des ann\u00e9es 1980. \u00c0 l&rsquo;\u00e9poque, la Stasi (police secr\u00e8te est-allemande) \u00e9tait la menace.<\/p>\n<p>Aujourd&rsquo;hui \u00e0 Bethl\u00e9em, ce sont les islamistes.<\/p>\n<p>Apr\u00e8s que les gardes aient jet\u00e9 un coup d&rsquo;\u0153il sur nos passeports am\u00e9ricains, mes amis am\u00e9ricains et moi-m\u00eame avons \u00e9t\u00e9 dirig\u00e9s vers le checkpoint qui s\u00e9pare Isra\u00ebl de l&rsquo;ancienne ville natale du roi David.<\/p>\n<p>A notre arriv\u00e9e, la m\u00e9fiance de nos h\u00f4tes me paraissait \u00e9trangement famili\u00e8re. Je pouvais presque lire dans leurs pens\u00e9es: \u00ab<em>Qui les a vus entrer dans notre maison? Qui pourrait \u00e9couter? Pouvons-nous faire confiance \u00e0 ces amis-amis?<\/em><\/p>\n<p>Pour moi, apr\u00e8s avoir visit\u00e9 Berlin avant que son mur inf\u00e2me ne tombe, l&rsquo;ambiance rappelait le mauvais vieux temps: la vie derri\u00e8re le rideau de fer.<\/p>\n<p>Mes amis et moi avons pass\u00e9 du temps avec, entre autres, une femme chr\u00e9tienne et sa petite famille. J&rsquo;aimerais pouvoir vous dire son nom. Et je voudrais beaucoup d\u00e9crire sa situation &#8211; ses besoins, sa lutte pour maintenir sa situation financi\u00e8re et les peurs sp\u00e9cifiques de sa famille.<\/p>\n<p>J&rsquo;aimerais aussi pouvoir utiliser de vrais noms quand j&rsquo;\u00e9cris sur d&rsquo;autres chr\u00e9tiens de Bethl\u00e9em &#8211; ceux que j&rsquo;ai rencontr\u00e9s et ceux dont j&rsquo;ai entendu parler par des amis de confiance.<\/p>\n<p>Pourquoi ne puis-je pas nommer des noms ou citer des emplacements? Parce que le moindre soup\u00e7on sur des chr\u00e9tiens de Bethl\u00e9em qui \u00ab<em>informeraient les \u00e9trangers<\/em>\u00bb sur les probl\u00e8mes auxquels ils sont confront\u00e9s pourrait tr\u00e8s bien les mettre en danger, sans parler de leurs amis et des membres de leur famille.<\/p>\n<h2>Qui est responsable des tensions?<\/h2>\n<p>Aujourd&rsquo;hui, une grande partie des tensions \u00e0 Bethl\u00e9em et ailleurs en Jud\u00e9e-Samarie est imput\u00e9e \u00e0 \u00ab\u00a0<em>l&rsquo;occupation isra\u00e9lienne<\/em>\u00a0\u00bb et \u00e0 la barri\u00e8re de s\u00e9curit\u00e9.<\/p>\n<p>\u00c0 certains endroits, y compris \u00e0 Bethl\u00e9em, il existe en effet un formidable mur militaire &#8211; qui rappelle \u00e9galement Berlin &#8211; officiellement appel\u00e9 \u00ab<em>barri\u00e8re de Cisjordanie<\/em>\u00bb. Il s\u00e9pare les communaut\u00e9s arabes de la population isra\u00e9lienne.<\/p>\n<p>Il est vrai que le mur est un encombrement pour les gens qui vivent derri\u00e8re. C&rsquo;est une pollution visuelle et, \u00e0 certains endroits, elle p\u00e8se lourdement sur les affaires et le commerce.<\/p>\n<p>Les postes de contr\u00f4le en Isra\u00ebl peuvent \u00eatre une nuisance. C\u2019est d\u2019autant plus vrai que les arabes et les isra\u00e9liens ont pu aller et venir sans restrictions jusqu\u2019\u00e0 ce que les accords de paix mal class\u00e9s d\u2019Oslo les privent de leur libert\u00e9 de mouvement.<\/p>\n<p>Mais le mur de s\u00e9curit\u00e9 a \u00e9galement sauv\u00e9 des vies isra\u00e9liennes. Il a \u00e9t\u00e9 \u00e9rig\u00e9 au cours de la deuxi\u00e8me Intifada, au cours de laquelle une succession sans fin d&rsquo;autobus explosifs, de pizzerias, de caf\u00e9s et d&rsquo;autres lieux publics a d\u00e9vast\u00e9 Isra\u00ebl pendant plus de trois ans, co\u00fbtant la vie \u00e0 plus de 1 000 personnes.<\/p>\n<p>Il est largement rapport\u00e9 qu&rsquo;apr\u00e8s la construction de la Barri\u00e8re de Cisjordanie, le nombre d&rsquo;attentats-suicides a diminu\u00e9 de plus de 90%.<\/p>\n<p>Aujourd&rsquo;hui, le terrorisme continue en Isra\u00ebl, mais son visage est diff\u00e9rent.<\/p>\n<p>Les palestiniens ciblent principalement les soldats et les juifs religieux qui vivant dans des colonies. Ces attaques sont sporadiques et impr\u00e9visibles: elles consistent \u00e0 poignarder avec des couteaux ou des machettes, \u00e0 foncer en voiture sur des groupes de personnes \u00e0 des arr\u00eats de bus ou \u00e0 lancer des pierres et des bombes sur les voitures et les autobus. Une attaque r\u00e9cente contre un caf\u00e9 branchait de Tel-Aviv impliquait m\u00eame des armes \u00e0 feu.<\/p>\n<p>Depuis septembre 2015, 40 personnes ont \u00e9t\u00e9 tu\u00e9es par ces attaques terroristes et 517 personnes ont \u00e9t\u00e9 bless\u00e9es.<\/p>\n<p>En ce qui concerne la barri\u00e8re de s\u00e9curit\u00e9, lorsque le cri palestinien de \u00ab\u00a0<em>d\u00e9chirez ce mur!<\/em>\u00a0\u00bb Est entendu en Isra\u00ebl, la r\u00e9ponse est provocante: \u00ab\u00a0<em>Arr\u00eatez le terrorisme ou oubliez (cette id\u00e9e)<\/em>\u00ab\u00a0.<\/p>\n<h2>La population chr\u00e9tienne palestinienne diminue<\/h2>\n<p>En attendant, il est clair que la population chr\u00e9tienne de Cisjordanie diminue. En 2013, Rosanna Rafel a rapport\u00e9 que \u00ab<em>dans la Palestine sous mandat britannique, avant la cr\u00e9ation d&rsquo;Isra\u00ebl en 1948, le pourcentage de la population chr\u00e9tienne s&rsquo;\u00e9levait \u00e0 18%. Ce chiffre est maintenant tomb\u00e9 \u00e0 moins de 1,5%. \u00ab\u00a0<\/em><\/p>\n<p>Cette chute de la population chr\u00e9tienne est invariablement attribu\u00e9e \u00e0 \u00ab<em>l&rsquo;occupation isra\u00e9lienne\u00bb<\/em>. Mais s&rsquo;il en est ainsi, pourquoi la population musulmane ne diminue-t-elle pas aussi?<\/p>\n<p>Les chr\u00e9tiens fuient la Cisjordanie du fait de la pers\u00e9cution anti-chr\u00e9tienne.<\/p>\n<p>A Bethl\u00e9em, les chr\u00e9tiens ne sont pas qu&rsquo;une minorit\u00e9 au sein d&rsquo;une communaut\u00e9 majoritairement musulmane. Ils ne sont pas simplement marginalis\u00e9s; ils ne souffrent pas seulement de discrimination. Trop souvent, ils sont menac\u00e9s et intimid\u00e9s; bless\u00e9 ou m\u00eame tu\u00e9s. Ils doivent \u00eatre prudents. Ils sont mal \u00e0 l&rsquo;aise. Beaucoup d&rsquo;entre eux vivent dans la peur.<\/p>\n<p>Dans le num\u00e9ro de mars 2016 du magazine Providence, le directeur ex\u00e9cutif du projet Philos, Robert Nicholson, a \u00e9crit un article convaincant: \u00ab<em>Pourquoi les chr\u00e9tiens palestiniens fuient-ils?\u00a0\u00bb<\/em><\/p>\n<p>Il y a expliqu\u00e9 que \u00ab\u00a0<em>l&rsquo;Autorit\u00e9 palestinienne &#8211; le gouvernement cr\u00e9\u00e9 par l&rsquo;OLP pour g\u00e9rer la Cisjordanie et Gaza &#8211; est, par sa propre constitution, un Etat islamique qui incarne les principes de la charia\u00a0\u00bb.<\/em><\/p>\n<p>Les chr\u00e9tiens vivant sous l&rsquo;AP sont \u00ab<em>sanctifi\u00e9s et respect\u00e9s<\/em>\u00bb, mais, comme c&rsquo;est le cas dans tous les syst\u00e8mes bas\u00e9s sur la charia, les chr\u00e9tiens sont rel\u00e9gu\u00e9s au statut de citoyens de seconde classe. Bien s\u00fbr, il est ill\u00e9gal de passer de l\u2019islam au christianisme. Ne parlons m\u00eame pas du fait que la vente de terres aux juifs est un crime passible de la peine de mort.<\/p>\n<p>La discrimination \u00e0 l&rsquo;encontre des chr\u00e9tiens sous l&rsquo;Autorit\u00e9 Palestinienne n&rsquo;est pas seulement l\u00e9gale &#8211; elle est \u00e9galement sociale. Vivant en tant que chr\u00e9tien, il est constamment rappel\u00e9 qu&rsquo;il ou elle n&rsquo;est pas membre de la culture majoritaire.<\/p>\n<p>Les chr\u00e9tiens de Bethl\u00e9em risquent d\u2019\u00eatre d\u00e9tenus par les autorit\u00e9s sur la base d\u2019accusations vagues. Un \u00ab<em>entretien<\/em>\u00bb avec les autorit\u00e9s locales peut conduire \u00e0 des menaces s\u00e9v\u00e8res ou, plus effrayant, \u00e0 une arrestation sur des accusations mont\u00e9es de toutes pi\u00e8ces.<\/p>\n<p>Lors de notre visite \u00e0 Bethl\u00e9em, mes amis et moi avons parl\u00e9 \u00e0 un ouvrier &#8211; nous l&rsquo;appellerons George &#8211; qui fait de l&rsquo;entretien ext\u00e9rieur pr\u00e8s d&rsquo;une \u00e9cole de Bethl\u00e9em. Cette ann\u00e9e, malgr\u00e9 une vague de chaleur intense, et malgr\u00e9 le fait qu&rsquo;il n&rsquo;est pas musulman, il a \u00e9t\u00e9 menac\u00e9 physiquement pour avoir publiquement bu une bouteille d&rsquo;eau pendant le Ramadan.<\/p>\n<p>Ailleurs, nous avons entendu parler d&rsquo;un propri\u00e9taire chr\u00e9tien qui avait lou\u00e9 un appartement \u00e0 une famille musulmane. Lorsque le loyer est arriv\u00e9 \u00e0 \u00e9ch\u00e9ance, les nouveaux locataires ont refus\u00e9 de payer. Cela a continu\u00e9 pendant des mois. Les autorit\u00e9s locales ont \u00e9t\u00e9 alert\u00e9es, mais elles ont simplement hauss\u00e9 les \u00e9paules. \u00ab\u00a0<em>Rien que nous puissions faire \u00e0 ce sujet<\/em>\u00ab\u00a0, ont-ils dit. \u00ab\u00a0<em>Nous avons les mains li\u00e9es.<\/em>\u00a0\u00bb<\/p>\n<p>Au cours des derni\u00e8res ann\u00e9es, plusieurs propri\u00e9t\u00e9s de l&rsquo;Eglise \u00e0 Bethl\u00e9em ont \u00e9t\u00e9 vandalis\u00e9es, incendi\u00e9es ou envahies par des intrus violents lors des c\u00e9l\u00e9brations ou des cultes. L&rsquo;application de la loi par l&rsquo;AP arrive g\u00e9n\u00e9ralement longtemps apr\u00e8s l&rsquo;appel d&rsquo;urgence &#8211; le cas \u00e9ch\u00e9ant.<\/p>\n<p>Lors d&rsquo;une r\u00e9cente trag\u00e9die, un jeune homme souffrant de retard mental et qui vit dans un village chr\u00e9tien (un de ses amis le qualifie de \u00ab\u00a0<em>gar\u00e7on b\u00e9ni\u00a0\u00bb<\/em>) a entendu des d\u00e9clarations antichr\u00e9tiennes offensantes \u00e9manant d\u2019une mosqu\u00e9e locale.<\/p>\n<p>Furieux, il a cri\u00e9 une insulte aux musulmans.<\/p>\n<p>Plus tard, il a post\u00e9 quelque chose d&rsquo;aussi anti-islamique sur Facebook.<\/p>\n<p>Quelques jours plus tard, le \u00ab\u00a0<em>gar\u00e7on b\u00e9ni<\/em>\u00a0\u00bb a disparu.<\/p>\n<p>Au moment o\u00f9 j&rsquo;\u00e9cris ces lignes, il a disparu depuis plus de trois mois. Sa famille est totalement traumatis\u00e9e, craignant de s\u2019adresser aux autorit\u00e9s locales. Ils craignent l&rsquo;annonce de nouvelles d\u00e9vastatrices et les repr\u00e9sailles mortelles.<\/p>\n<p>Nous-m\u00eames avons \u00e9t\u00e9 b\u00e9nis, \u00e9coutant et apprenant des chr\u00e9tiens que nous avons visit\u00e9s. Nous rencontrer \u00e9tait un acte de grand courage de leur part. Pour nous, c&rsquo;\u00e9tait une opportunit\u00e9 extraordinaire.<\/p>\n<p>Comme Nicholson l&rsquo;a \u00e9crit,<\/p>\n<p>J&rsquo;ai parl\u00e9 \u00e0 de nombreux chr\u00e9tiens palestiniens qui d\u00e9crivent comment des terroristes musulmans r\u00e9quisitionneraient des maisons chr\u00e9tiennes et les utilisent pour diriger des tirs de snipers sur des soldats isra\u00e9liens. D&rsquo;autres parlent de discrimination syst\u00e9matique dans le recrutement, le logement et l&rsquo;\u00e9ducation. Bien s\u00fbr, toutes ces conversations ont lieu lors des r\u00e9unions priv\u00e9es et des tons feutr\u00e9s.<\/p>\n<p>Les chr\u00e9tiens de Bethl\u00e9em interagissent rarement avec les musulmans au-del\u00e0 du march\u00e9 et, en fait, ont tr\u00e8s peur. Mais en public, les chr\u00e9tiens palestiniens assimilent leur situation \u00e0 celle de leurs voisins musulmans et louent la coexistence heureuse entre les deux groupes.<\/p>\n<p>Ils n&rsquo;ont pas le choix.<\/p>\n<p>Ils sont otages dans leur propre ville.<\/p>\n<p>* * *<\/p>\n<p><em>Lela Gilbert r\u00e9dige une chronique hebdomadaire sur Foi et Libert\u00e9 pour Newsmax. Elle est expert internationalement reconnu sur la pers\u00e9cution religieuse, \u00e9crivain prim\u00e9, et coll\u00e8gue auxiliaire \u00e0 l&rsquo;Institut Hudson, ayant v\u00e9cu \u00e0 J\u00e9rusalem pendant plus d&rsquo;une d\u00e9cennie. Son livre \u00ab\u00a0Les gens du samedi, les gens du dimanche: Isra\u00ebl \u00e0 travers les yeux d&rsquo;un chr\u00e9tien qui s\u00e9journe\u00a0\u00bb a \u00e9t\u00e9 largement acclam\u00e9 par la critique. Elle est \u00e9galement co-auteur de \u00abPers\u00e9cut\u00e9e: l&rsquo;assaut global contre les chr\u00e9tiens\u00bb et \u00abAveugle: quand les journalistes ne comprennent pas la religion\u00bb. Suivez-la sur Twitter<\/em><\/p>\n<shortcode  style=\"display:block\" ><div class=\"cta-boxed\"><h2>Do You Love Israel? Make a Donation - Show Your Support!<\/h2><div class=\"wp-caption alignright\" style=\"width: 260px\"><a href=\"https:\/\/donate.unitedwithisrael.org\/donate\/g4?a=asc\"><img decoding=\"async\" class=\"size-medium\" src=\"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2022\/06\/shutterstock_1528562331.jpeg\" alt=\"\" width=\"260\"><\/a><p class=\"wp-caption-text\"><\/p><\/div><p><a href=\"https:\/\/donate.unitedwithisrael.org\/donate\/g4?a=asc\" target=\"_blank\" rel=\"noopener\"><strong>Donate to vital charities<\/strong><\/a> that help protect Israeli citizens and inspire millions around the world to support Israel too! <\/p><p> Now more than ever, Israel needs your help to fight and win the war -- including on the battlefield of public opinion. <\/p><p> Antisemitism, anti-Israel bias and boycotts are out of control. Israel's enemies are inciting terror and violence against innocent Israelis and Jews around the world. <a href=\"https:\/\/donate.unitedwithisrael.org\/donate\/g4?a=asc\" target=\"_blank\" rel=\"noopener\"><strong>Help us fight back!<\/strong><\/a>  <\/p> <p style=\"text-align: left;\"><strong><a href=\"https:\/\/donate.unitedwithisrael.org\/donate\/g4?a=asc\" target=\"_blank\">STAND WTH ISRAEL - MAKE A DONATION TODAY!<\/a><\/strong><\/p><\/div><\/shortcode><non-auwi><ad-shortcode><div style=\"margin-top:20px;display:block\"><a href=\"https:\/\/donate.unitedwithisrael.org\/donate\/G1S\/?a=uwi_es_art_bnr_atk\"><img decoding=\"async\" class=\"no-border\" style=\"padding:0;\" src=\"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2015\/11\/ad_890x100_es.jpg\" alt=\"Donate to Israel\" \/><\/a><\/div><\/ad-shortcode><\/non-auwi>","protected":false},"excerpt":{"rendered":"<p>\u00abJe n&rsquo;ai jamais \u00e9t\u00e9 victime de discrimination en tant que chr\u00e9tienne vivant en Isra\u00ebl\u00bb, explique Lela Gilbert. Par: Lela Gilbert, en exclusivit\u00e9 pour Unis avec Isra\u00ebl Un article r\u00e9cent, \u00ab\u00a0Les chr\u00e9tiens ne sont plus les bienvenus en Isra\u00ebl &#8211; Des terres confisqu\u00e9es pour les colonies isra\u00e9liennes\u00a0\u00bb (aucun nom d&rsquo;auteur n&rsquo;est fourni) a \u00e9t\u00e9 publi\u00e9 par&#8230;  <a href=\"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/\" class=\"more-link\" title=\"Read donate\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":4242,"featured_media":264931,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[28411],"tags":[28897,28491,31160,31158,29147,31159,30491,23049,28574,14259],"class_list":["post-264915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflit-arabo-israelien","tag-autorite-palestinienne","tag-chretiens","tag-eglise","tag-leila-gilbert","tag-liberte","tag-liberte-de-culte","tag-menaces","tag-oppression","tag-palestiniens","tag-religion"],"better_featured_image":{"id":264931,"alt_text":"","caption":"Bethlehem","description":"","media_type":"image","media_details":{"width":1000,"height":659,"file":"2018\/08\/shutterstock_767023351.jpg","sizes":{"thumbnail":{"file":"shutterstock_767023351-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-150x150.jpg"},"medium":{"file":"shutterstock_767023351-300x198.jpg","width":300,"height":198,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-300x198.jpg"},"medium_large":{"file":"shutterstock_767023351-768x506.jpg","width":768,"height":506,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-768x506.jpg"},"uwi-full-width":{"file":"shutterstock_767023351-780x514.jpg","width":780,"height":514,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-780x514.jpg"},"uwi-featured-carousel":{"file":"shutterstock_767023351-890x400.jpg","width":890,"height":400,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-890x400.jpg"},"uwi-featured-content":{"file":"shutterstock_767023351-290x160.jpg","width":290,"height":160,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-290x160.jpg"},"uwi-content-loop":{"file":"shutterstock_767023351-190x190.jpg","width":190,"height":190,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-190x190.jpg"},"uwi-category_list":{"file":"shutterstock_767023351-180x100.jpg","width":180,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-180x100.jpg"},"uwi-tiny":{"file":"shutterstock_767023351-40x40.jpg","width":40,"height":40,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-40x40.jpg"},"uwi-email-featured":{"file":"shutterstock_767023351-250x170.jpg","width":250,"height":170,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-250x170.jpg"},"uwi-email":{"file":"shutterstock_767023351-200x140.jpg","width":200,"height":140,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-200x140.jpg"},"uwi-iphone":{"file":"shutterstock_767023351-960x640.jpg","width":960,"height":640,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-960x640.jpg"},"uwi-iphone-x2":{"file":"shutterstock_767023351-1000x640.jpg","width":1000,"height":640,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-1000x640.jpg"},"uwi-full-width-video":{"file":"shutterstock_767023351-779x513.jpg","width":779,"height":513,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-779x513.jpg"},"uwi-fb-share-video":{"file":"shutterstock_767023351-600x315.jpg","width":600,"height":315,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-600x315.jpg"},"uwi-fb-share":{"file":"shutterstock_767023351-600x320.jpg","width":600,"height":320,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-600x320.jpg"},"uwi-featured-content-video":{"file":"shutterstock_767023351-289x159.jpg","width":289,"height":159,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-289x159.jpg"},"uwi-content-loop-video":{"file":"shutterstock_767023351-189x189.jpg","width":189,"height":189,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-189x189.jpg"},"uwi-category_list-video":{"file":"shutterstock_767023351-179x99.jpg","width":179,"height":99,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-179x99.jpg"},"uwi-tiny-video":{"file":"shutterstock_767023351-39x39.jpg","width":39,"height":39,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-39x39.jpg"},"uwi-email-featured-video":{"file":"shutterstock_767023351-249x169.jpg","width":249,"height":169,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-249x169.jpg"},"uwi-email-video":{"file":"shutterstock_767023351-209x139.jpg","width":209,"height":139,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-209x139.jpg"},"uwi-iphone-video":{"file":"shutterstock_767023351-959x639.jpg","width":959,"height":639,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-959x639.jpg"},"uwi-iphone-x2-video":{"file":"shutterstock_767023351-1000x639.jpg","width":1000,"height":639,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-1000x639.jpg"},"post-thumbnail":{"file":"shutterstock_767023351-125x125.jpg","width":125,"height":125,"mime-type":"image\/jpeg","source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351-125x125.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":264915,"source_url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2018\/08\/shutterstock_767023351.jpg"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Donate to vital charities that help protect Israeli citizens and inspire millions around the world to support Israel too! Now more than ever, Israel needs your help to fight and win the war -- including on the battlefield of public opinion. Antisemitism, anti-Israel bias and boycotts are out of control. Israel&#039;s enemies are inciting terror\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"mocheaz\"\/>\n\t<meta name=\"google-site-verification\" content=\"fm8mGYa0Z7ldfcvOcaXponxu6m6wMhDwN4IJKdLnPwc\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Unis avec Isra\u00ebl | Join the world&#039;s largest pro-Israel community with over 9 million members! By sharing biblical, historical and modern perspectives, we promote worldwide unity with the People, Country and Land of Israel. Join here --&gt; https:\/\/unitedwithisrael.org\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"donate | Unis avec Isra\u00ebl\" \/>\n\t\t<meta property=\"og:description\" content=\"Donate to vital charities that help protect Israeli citizens and inspire millions around the world to support Israel too! Now more than ever, Israel needs your help to fight and win the war -- including on the battlefield of public opinion. Antisemitism, anti-Israel bias and boycotts are out of control. Israel&#039;s enemies are inciting terror\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-06-13T09:00:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-10T11:52:46+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unitedwithisrael\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/uwi_shortcodes\\\/donate\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/category\\\/conflit-arabo-israelien\\\/#listItem\",\"name\":\"Conflit arabo-Isra\\u00e9lien\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/category\\\/conflit-arabo-israelien\\\/#listItem\",\"position\":2,\"name\":\"Conflit arabo-Isra\\u00e9lien\",\"item\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/category\\\/conflit-arabo-israelien\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/temoignage-exclusif-etre-chretien-en-zone-controlee-par-lautorite-palestinienne\\\/#listItem\",\"name\":\"T\\u00e9moignage exclusif: Etre chr\\u00e9tien en zone contr\\u00f4l\\u00e9e par l&rsquo;Autorit\\u00e9 Palestinienne\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/temoignage-exclusif-etre-chretien-en-zone-controlee-par-lautorite-palestinienne\\\/#listItem\",\"position\":3,\"name\":\"T\\u00e9moignage exclusif: Etre chr\\u00e9tien en zone contr\\u00f4l\\u00e9e par l&rsquo;Autorit\\u00e9 Palestinienne\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/category\\\/conflit-arabo-israelien\\\/#listItem\",\"name\":\"Conflit arabo-Isra\\u00e9lien\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/#organization\",\"name\":\"United with Israel\",\"description\":\"Join the world's largest pro-Israel community with over 9 million members! By sharing biblical, historical and modern perspectives, we promote worldwide unity with the People, Country and Land of Israel. Join here --> https:\\\/\\\/unitedwithisrael.org\",\"url\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/\",\"telephone\":\"+15163951933\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/unitedwithisrael\",\"https:\\\/\\\/twitter.com\\\/UniteWithIsrael\",\"https:\\\/\\\/www.instagram.com\\\/unitewithisrael\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/unitewithisrael\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/unitedwithisrael\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/author\\\/mocheaz\\\/#author\",\"url\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/author\\\/mocheaz\\\/\",\"name\":\"mocheaz\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/uwi_shortcodes\\\/donate\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f175a2fd6dd9e94494e11a2eb18f8592271a2838bb87de4e7c782b3e1430da8?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"mocheaz\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/uwi_shortcodes\\\/donate\\\/#webpage\",\"url\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/uwi_shortcodes\\\/donate\\\/\",\"name\":\"donate | Unis avec Isra\\u00ebl\",\"description\":\"Donate to vital charities that help protect Israeli citizens and inspire millions around the world to support Israel too! Now more than ever, Israel needs your help to fight and win the war -- including on the battlefield of public opinion. Antisemitism, anti-Israel bias and boycotts are out of control. Israel's enemies are inciting terror\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/uwi_shortcodes\\\/donate\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/author\\\/mocheaz\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/author\\\/mocheaz\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/unitedwithisrael.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/shutterstock_1528562331.jpeg\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/uwi_shortcodes\\\/donate\\\/#mainImage\",\"width\":800,\"height\":460},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/uwi_shortcodes\\\/donate\\\/#mainImage\"},\"datePublished\":\"2022-06-13T09:00:03+03:00\",\"dateModified\":\"2026-04-10T14:52:46+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/\",\"name\":\"United with Israel\",\"description\":\"Join the world's largest pro-Israel community with over 9 million members! By sharing biblical, historical and modern perspectives, we promote worldwide unity with the People, Country and Land of Israel. Join here --> https:\\\/\\\/unitedwithisrael.org\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/unitedwithisrael.org\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"donate | Unis avec Isra\u00ebl","description":"Donate to vital charities that help protect Israeli citizens and inspire millions around the world to support Israel too! Now more than ever, Israel needs your help to fight and win the war -- including on the battlefield of public opinion. Antisemitism, anti-Israel bias and boycotts are out of control. Israel's enemies are inciting terror","canonical_url":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"fm8mGYa0Z7ldfcvOcaXponxu6m6wMhDwN4IJKdLnPwc","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/unitedwithisrael.org\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/unitedwithisrael.org\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/unitedwithisrael.org\/fr\/category\/conflit-arabo-israelien\/#listItem","name":"Conflit arabo-Isra\u00e9lien"}},{"@type":"ListItem","@id":"https:\/\/unitedwithisrael.org\/fr\/category\/conflit-arabo-israelien\/#listItem","position":2,"name":"Conflit arabo-Isra\u00e9lien","item":"https:\/\/unitedwithisrael.org\/fr\/category\/conflit-arabo-israelien\/","nextItem":{"@type":"ListItem","@id":"https:\/\/unitedwithisrael.org\/fr\/temoignage-exclusif-etre-chretien-en-zone-controlee-par-lautorite-palestinienne\/#listItem","name":"T\u00e9moignage exclusif: Etre chr\u00e9tien en zone contr\u00f4l\u00e9e par l&rsquo;Autorit\u00e9 Palestinienne"},"previousItem":{"@type":"ListItem","@id":"https:\/\/unitedwithisrael.org\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/unitedwithisrael.org\/fr\/temoignage-exclusif-etre-chretien-en-zone-controlee-par-lautorite-palestinienne\/#listItem","position":3,"name":"T\u00e9moignage exclusif: Etre chr\u00e9tien en zone contr\u00f4l\u00e9e par l&rsquo;Autorit\u00e9 Palestinienne","previousItem":{"@type":"ListItem","@id":"https:\/\/unitedwithisrael.org\/fr\/category\/conflit-arabo-israelien\/#listItem","name":"Conflit arabo-Isra\u00e9lien"}}]},{"@type":"Organization","@id":"https:\/\/unitedwithisrael.org\/fr\/#organization","name":"United with Israel","description":"Join the world's largest pro-Israel community with over 9 million members! By sharing biblical, historical and modern perspectives, we promote worldwide unity with the People, Country and Land of Israel. Join here --> https:\/\/unitedwithisrael.org","url":"https:\/\/unitedwithisrael.org\/fr\/","telephone":"+15163951933","sameAs":["https:\/\/www.facebook.com\/unitedwithisrael","https:\/\/twitter.com\/UniteWithIsrael","https:\/\/www.instagram.com\/unitewithisrael\/","https:\/\/www.pinterest.com\/unitewithisrael\/","https:\/\/www.youtube.com\/user\/unitedwithisrael"]},{"@type":"Person","@id":"https:\/\/unitedwithisrael.org\/fr\/author\/mocheaz\/#author","url":"https:\/\/unitedwithisrael.org\/fr\/author\/mocheaz\/","name":"mocheaz","image":{"@type":"ImageObject","@id":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6f175a2fd6dd9e94494e11a2eb18f8592271a2838bb87de4e7c782b3e1430da8?s=96&d=mm&r=g","width":96,"height":96,"caption":"mocheaz"}},{"@type":"WebPage","@id":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/#webpage","url":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/","name":"donate | Unis avec Isra\u00ebl","description":"Donate to vital charities that help protect Israeli citizens and inspire millions around the world to support Israel too! Now more than ever, Israel needs your help to fight and win the war -- including on the battlefield of public opinion. Antisemitism, anti-Israel bias and boycotts are out of control. Israel's enemies are inciting terror","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/unitedwithisrael.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/#breadcrumblist"},"author":{"@id":"https:\/\/unitedwithisrael.org\/fr\/author\/mocheaz\/#author"},"creator":{"@id":"https:\/\/unitedwithisrael.org\/fr\/author\/mocheaz\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/unitedwithisrael.org\/wp-content\/uploads\/2022\/06\/shutterstock_1528562331.jpeg","@id":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/#mainImage","width":800,"height":460},"primaryImageOfPage":{"@id":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/#mainImage"},"datePublished":"2022-06-13T09:00:03+03:00","dateModified":"2026-04-10T14:52:46+03:00"},{"@type":"WebSite","@id":"https:\/\/unitedwithisrael.org\/fr\/#website","url":"https:\/\/unitedwithisrael.org\/fr\/","name":"United with Israel","description":"Join the world's largest pro-Israel community with over 9 million members! By sharing biblical, historical and modern perspectives, we promote worldwide unity with the People, Country and Land of Israel. Join here --> https:\/\/unitedwithisrael.org","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/unitedwithisrael.org\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Unis avec Isra\u00ebl | Join the world's largest pro-Israel community with over 9 million members! By sharing biblical, historical and modern perspectives, we promote worldwide unity with the People, Country and Land of Israel. Join here --&gt; https:\/\/unitedwithisrael.org","og:type":"article","og:title":"donate | Unis avec Isra\u00ebl","og:description":"Donate to vital charities that help protect Israeli citizens and inspire millions around the world to support Israel too! Now more than ever, Israel needs your help to fight and win the war -- including on the battlefield of public opinion. Antisemitism, anti-Israel bias and boycotts are out of control. Israel's enemies are inciting terror","og:url":"https:\/\/unitedwithisrael.org\/fr\/uwi_shortcodes\/donate\/","article:published_time":"2022-06-13T09:00:03+00:00","article:modified_time":"2026-04-10T11:52:46+00:00","article:publisher":"https:\/\/www.facebook.com\/unitedwithisrael"},"aioseo_meta_data":{"post_id":"264915","title":"T\u00e9moignage exclusif: Etre chr\u00e9tien en zone contr\u00f4l\u00e9e par l'Autorit\u00e9 Palestinienne | #site_title","description":"\u00abJe n'ai jamais \u00e9t\u00e9 victime de discrimination en tant que chr\u00e9tienne vivant en Isra\u00ebl\u00bb, explique Lela Gilbert.","keywords":[{"label":"Leila Gilbert","value":"Leila Gilbert"},{"label":"chr\u00e9tiens","value":"chr\u00e9tiens"},{"label":"palestiniens","value":"palestiniens"},{"label":"Autorit\u00e9 Palestinienne","value":"Autorit\u00e9 Palestinienne"},{"label":"religion","value":"religion"},{"label":"libert\u00e9","value":"libert\u00e9"},{"label":"libert\u00e9 de culte","value":"libert\u00e9 de culte"},{"label":"menaces","value":"menaces"},{"label":"Eglise","value":"Eglise"},{"label":"oppression","value":"oppression"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-25 21:21:12","updated":"2022-11-22 09:47:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/unitedwithisrael.org\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/unitedwithisrael.org\/fr\/category\/conflit-arabo-israelien\/\" title=\"Conflit arabo-Isra\u00e9lien\">Conflit arabo-Isra\u00e9lien<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tT\u00e9moignage exclusif: Etre chr\u00e9tien en zone contr\u00f4l\u00e9e par l\u2019Autorit\u00e9 Palestinienne\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/unitedwithisrael.org\/fr\/"},{"label":"Conflit arabo-Isra\u00e9lien","link":"https:\/\/unitedwithisrael.org\/fr\/category\/conflit-arabo-israelien\/"},{"label":"T\u00e9moignage exclusif: Etre chr\u00e9tien en zone contr\u00f4l\u00e9e par l&rsquo;Autorit\u00e9 Palestinienne","link":"https:\/\/unitedwithisrael.org\/fr\/temoignage-exclusif-etre-chretien-en-zone-controlee-par-lautorite-palestinienne\/"}],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Unis avec Isra\u00ebl","distributor_original_site_url":"https:\/\/unitedwithisrael.org\/fr\/","push-errors":false,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/posts\/264915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/users\/4242"}],"replies":[{"embeddable":true,"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/comments?post=264915"}],"version-history":[{"count":0,"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/posts\/264915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/media\/264931"}],"wp:attachment":[{"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/media?parent=264915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/categories?post=264915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unitedwithisrael.org\/fr\/wp-json\/wp\/v2\/tags?post=264915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}